{"id":4264,"date":"2021-02-26T09:37:12","date_gmt":"2021-02-26T09:37:12","guid":{"rendered":"https:\/\/ulexproject.org\/?post_type=courses_events&#038;p=4264"},"modified":"2025-05-29T11:16:35","modified_gmt":"2025-05-29T11:16:35","slug":"lgbtqi-psycho-social-resilience-central-eastern-europe-4-month-long-online-training","status":"publish","type":"courses_events","link":"https:\/\/ulexproject.org\/es\/courses_events\/lgbtqi-psycho-social-resilience-central-eastern-europe-4-month-long-online-training\/","title":{"rendered":"LGBTQI+ Psycho-Social Resilience online training"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":1942,"template":"","tags_courses_events":[],"categories_courses_events":[],"class_list":["post-4264","courses_events","type-courses_events","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LGBTQI+ Psycho-Social Resilience online training - Ulex<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ulexproject.org\/es\/courses_events\/lgbtqi-psycho-social-resilience-central-eastern-europe-4-month-long-online-training\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LGBTQI+ Psycho-Social Resilience online training - Ulex\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ulexproject.org\/es\/courses_events\/lgbtqi-psycho-social-resilience-central-eastern-europe-4-month-long-online-training\/\" \/>\n<meta property=\"og:site_name\" content=\"Ulex\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-29T11:16:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ulexproject.org\/wp-content\/uploads\/2018\/02\/dimanno-pride.jpg.size_.custom.crop_.1086x738-e1596027934843.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ulexproject.org\\\/es\\\/courses_events\\\/lgbtqi-psycho-social-resilience-central-eastern-europe-4-month-long-online-training\\\/\",\"url\":\"https:\\\/\\\/ulexproject.org\\\/es\\\/courses_events\\\/lgbtqi-psycho-social-resilience-central-eastern-europe-4-month-long-online-training\\\/\",\"name\":\"LGBTQI+ Psycho-Social Resilience online training - Ulex\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ulexproject.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ulexproject.org\\\/es\\\/courses_events\\\/lgbtqi-psycho-social-resilience-central-eastern-europe-4-month-long-online-training\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ulexproject.org\\\/es\\\/courses_events\\\/lgbtqi-psycho-social-resilience-central-eastern-europe-4-month-long-online-training\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ulexproject.org\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/dimanno-pride.jpg.size_.custom.crop_.1086x738-e1596027934843.jpg\",\"datePublished\":\"2021-02-26T09:37:12+00:00\",\"dateModified\":\"2025-05-29T11:16:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ulexproject.org\\\/es\\\/courses_events\\\/lgbtqi-psycho-social-resilience-central-eastern-europe-4-month-long-online-training\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ulexproject.org\\\/es\\\/courses_events\\\/lgbtqi-psycho-social-resilience-central-eastern-europe-4-month-long-online-training\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ulexproject.org\\\/es\\\/courses_events\\\/lgbtqi-psycho-social-resilience-central-eastern-europe-4-month-long-online-training\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ulexproject.org\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/dimanno-pride.jpg.size_.custom.crop_.1086x738-e1596027934843.jpg\",\"contentUrl\":\"https:\\\/\\\/ulexproject.org\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/dimanno-pride.jpg.size_.custom.crop_.1086x738-e1596027934843.jpg\",\"width\":800,\"height\":200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ulexproject.org\\\/es\\\/courses_events\\\/lgbtqi-psycho-social-resilience-central-eastern-europe-4-month-long-online-training\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ulexproject.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Courses\",\"item\":\"https:\\\/\\\/ulexproject.org\\\/es\\\/courses_events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"LGBTQI+ Psycho-Social Resilience online training\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ulexproject.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ulexproject.org\\\/es\\\/\",\"name\":\"Ulex\",\"description\":\"TRAININGS FOR SOCIAL MOVEMENT IMPACT &amp; RESILIENCE\",\"publisher\":{\"@id\":\"https:\\\/\\\/ulexproject.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ulexproject.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ulexproject.org\\\/es\\\/#organization\",\"name\":\"Ulex\",\"url\":\"https:\\\/\\\/ulexproject.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ulexproject.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ulexproject.org\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/ulex-new-logo.png\",\"contentUrl\":\"https:\\\/\\\/ulexproject.org\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/ulex-new-logo.png\",\"width\":250,\"height\":133,\"caption\":\"Ulex\"},\"image\":{\"@id\":\"https:\\\/\\\/ulexproject.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LGBTQI+ Psycho-Social Resilience online training - Ulex","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ulexproject.org\/es\/courses_events\/lgbtqi-psycho-social-resilience-central-eastern-europe-4-month-long-online-training\/","og_locale":"es_ES","og_type":"article","og_title":"LGBTQI+ Psycho-Social Resilience online training - Ulex","og_url":"https:\/\/ulexproject.org\/es\/courses_events\/lgbtqi-psycho-social-resilience-central-eastern-europe-4-month-long-online-training\/","og_site_name":"Ulex","article_modified_time":"2025-05-29T11:16:35+00:00","og_image":[{"width":800,"height":200,"url":"https:\/\/ulexproject.org\/wp-content\/uploads\/2018\/02\/dimanno-pride.jpg.size_.custom.crop_.1086x738-e1596027934843.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ulexproject.org\/es\/courses_events\/lgbtqi-psycho-social-resilience-central-eastern-europe-4-month-long-online-training\/","url":"https:\/\/ulexproject.org\/es\/courses_events\/lgbtqi-psycho-social-resilience-central-eastern-europe-4-month-long-online-training\/","name":"LGBTQI+ Psycho-Social Resilience online training - Ulex","isPartOf":{"@id":"https:\/\/ulexproject.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ulexproject.org\/es\/courses_events\/lgbtqi-psycho-social-resilience-central-eastern-europe-4-month-long-online-training\/#primaryimage"},"image":{"@id":"https:\/\/ulexproject.org\/es\/courses_events\/lgbtqi-psycho-social-resilience-central-eastern-europe-4-month-long-online-training\/#primaryimage"},"thumbnailUrl":"https:\/\/ulexproject.org\/wp-content\/uploads\/2018\/02\/dimanno-pride.jpg.size_.custom.crop_.1086x738-e1596027934843.jpg","datePublished":"2021-02-26T09:37:12+00:00","dateModified":"2025-05-29T11:16:35+00:00","breadcrumb":{"@id":"https:\/\/ulexproject.org\/es\/courses_events\/lgbtqi-psycho-social-resilience-central-eastern-europe-4-month-long-online-training\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ulexproject.org\/es\/courses_events\/lgbtqi-psycho-social-resilience-central-eastern-europe-4-month-long-online-training\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ulexproject.org\/es\/courses_events\/lgbtqi-psycho-social-resilience-central-eastern-europe-4-month-long-online-training\/#primaryimage","url":"https:\/\/ulexproject.org\/wp-content\/uploads\/2018\/02\/dimanno-pride.jpg.size_.custom.crop_.1086x738-e1596027934843.jpg","contentUrl":"https:\/\/ulexproject.org\/wp-content\/uploads\/2018\/02\/dimanno-pride.jpg.size_.custom.crop_.1086x738-e1596027934843.jpg","width":800,"height":200},{"@type":"BreadcrumbList","@id":"https:\/\/ulexproject.org\/es\/courses_events\/lgbtqi-psycho-social-resilience-central-eastern-europe-4-month-long-online-training\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ulexproject.org\/es\/"},{"@type":"ListItem","position":2,"name":"Courses","item":"https:\/\/ulexproject.org\/es\/courses_events\/"},{"@type":"ListItem","position":3,"name":"LGBTQI+ Psycho-Social Resilience online training"}]},{"@type":"WebSite","@id":"https:\/\/ulexproject.org\/es\/#website","url":"https:\/\/ulexproject.org\/es\/","name":"Ulex","description":"TRAININGS FOR SOCIAL MOVEMENT IMPACT &amp; RESILIENCE","publisher":{"@id":"https:\/\/ulexproject.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ulexproject.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/ulexproject.org\/es\/#organization","name":"Ulex","url":"https:\/\/ulexproject.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ulexproject.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/ulexproject.org\/wp-content\/uploads\/2016\/10\/ulex-new-logo.png","contentUrl":"https:\/\/ulexproject.org\/wp-content\/uploads\/2016\/10\/ulex-new-logo.png","width":250,"height":133,"caption":"Ulex"},"image":{"@id":"https:\/\/ulexproject.org\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/ulexproject.org\/es\/wp-json\/wp\/v2\/course-events\/4264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ulexproject.org\/es\/wp-json\/wp\/v2\/course-events"}],"about":[{"href":"https:\/\/ulexproject.org\/es\/wp-json\/wp\/v2\/types\/courses_events"}],"version-history":[{"count":1,"href":"https:\/\/ulexproject.org\/es\/wp-json\/wp\/v2\/course-events\/4264\/revisions"}],"predecessor-version":[{"id":9051,"href":"https:\/\/ulexproject.org\/es\/wp-json\/wp\/v2\/course-events\/4264\/revisions\/9051"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ulexproject.org\/es\/wp-json\/wp\/v2\/media\/1942"}],"wp:attachment":[{"href":"https:\/\/ulexproject.org\/es\/wp-json\/wp\/v2\/media?parent=4264"}],"wp:term":[{"taxonomy":"tags_courses_events","embeddable":true,"href":"https:\/\/ulexproject.org\/es\/wp-json\/wp\/v2\/tags_courses_events?post=4264"},{"taxonomy":"categories_courses_events","embeddable":true,"href":"https:\/\/ulexproject.org\/es\/wp-json\/wp\/v2\/categories_courses_events?post=4264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}